{"id":64,"date":"2025-05-10T13:55:45","date_gmt":"2025-05-10T13:55:45","guid":{"rendered":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/?p=64"},"modified":"2025-05-10T13:55:46","modified_gmt":"2025-05-10T13:55:46","slug":"ccp-strategy-mini-retreat-2025","status":"publish","type":"post","link":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/","title":{"rendered":"CCP Strategy Mini Retreat 2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/image-31.jpg\" alt=\"\" class=\"wp-image-73\" srcset=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/image-31.jpg 800w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/image-31-300x200.jpg 300w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/image-31-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-1024x683.jpg\" alt=\"\" class=\"wp-image-67\" srcset=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-1024x683.jpg 1024w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-300x200.jpg 300w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-768x512.jpg 768w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-1536x1024.jpg 1536w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5664-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-1024x683.jpg\" alt=\"\" class=\"wp-image-69\" srcset=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-1024x683.jpg 1024w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-300x200.jpg 300w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-768x512.jpg 768w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-1536x1024.jpg 1536w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5666-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-1024x683.jpg\" alt=\"\" class=\"wp-image-68\" srcset=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-1024x683.jpg 1024w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-300x200.jpg 300w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-768x512.jpg 768w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-1536x1024.jpg 1536w, https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5665-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In a world where the built industry is constantly evolving and pivoting, staying ahead means more than just keeping pace with trends\u2014it requires vision, reflection, and deliberate planning. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The CCP team hit pause on deadlines and site visits to do something a little different\u2014we organized a strategy retreat hosted by Mr. Gbolaro Olulade! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As we continue to grow and take on increasingly complex and diverse projects, we recognized the importance of stepping away from our desks to think critically about our direction. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The strategy retreat was designed to give our leadership team and key staff members a dedicated space to assess our achievements, confront challenges, and forge new paths. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We reflected on our journey so far, suggested ambitious goals for short, mid and long-term, aimed at elevating our impact and increasing profitability. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We left the meeting with fresh energies and clarified vision, looking into the future with great possibilities. At CCP, the future is not something we wait for, it\u2019s something we build, one step at a time. #ccp #strategy #businessdevelopment #retreat #innovation #economicintelligence<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In a world where the built industry is constantly evolving and pivoting, staying ahead means more than just keeping pace with trends\u2014it requires vision, reflection, and deliberate planning. The CCP&hellip;<\/p>\n","protected":false},"author":2,"featured_media":72,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CCP Strategy Mini Retreat 2025 - CCP Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CCP Strategy Mini Retreat 2025 - CCP Blog\" \/>\n<meta property=\"og:description\" content=\"In a world where the built industry is constantly evolving and pivoting, staying ahead means more than just keeping pace with trends\u2014it requires vision, reflection, and deliberate planning. The CCP&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"CCP Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-10T13:55:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-10T13:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adeboye Lawal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adeboye Lawal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/\"},\"author\":{\"name\":\"Adeboye Lawal\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#\\\/schema\\\/person\\\/99025ad5d3769a666a3ccdd7edd2da98\"},\"headline\":\"CCP Strategy Mini Retreat 2025\",\"datePublished\":\"2025-05-10T13:55:45+00:00\",\"dateModified\":\"2025-05-10T13:55:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/\"},\"wordCount\":181,\"publisher\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_5669-scaled.jpg\",\"articleSection\":[\"Blog Post\"],\"inLanguage\":\"en\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/\",\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/\",\"name\":\"CCP Strategy Mini Retreat 2025 - CCP Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_5669-scaled.jpg\",\"datePublished\":\"2025-05-10T13:55:45+00:00\",\"dateModified\":\"2025-05-10T13:55:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_5669-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/IMG_5669-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/uncategorized\\\/ccp-strategy-mini-retreat-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CCP Strategy Mini Retreat 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#website\",\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/\",\"name\":\"CCP Blog\",\"description\":\"Consultants Collaborative Partnership Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#organization\",\"name\":\"CCP Blog\",\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-ccp-logo-header.png\",\"contentUrl\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-ccp-logo-header.png\",\"width\":61,\"height\":100,\"caption\":\"CCP Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/#\\\/schema\\\/person\\\/99025ad5d3769a666a3ccdd7edd2da98\",\"name\":\"Adeboye Lawal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g\",\"caption\":\"Adeboye Lawal\"},\"url\":\"https:\\\/\\\/www.consultantscollaborative.com\\\/ccp-blog\\\/author\\\/adeboye\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CCP Strategy Mini Retreat 2025 - CCP Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/","og_locale":"en_US","og_type":"article","og_title":"CCP Strategy Mini Retreat 2025 - CCP Blog","og_description":"In a world where the built industry is constantly evolving and pivoting, staying ahead means more than just keeping pace with trends\u2014it requires vision, reflection, and deliberate planning. The CCP&hellip;","og_url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/","og_site_name":"CCP Blog","article_published_time":"2025-05-10T13:55:45+00:00","article_modified_time":"2025-05-10T13:55:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg","type":"image\/jpeg"}],"author":"Adeboye Lawal","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Adeboye Lawal","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#article","isPartOf":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/"},"author":{"name":"Adeboye Lawal","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#\/schema\/person\/99025ad5d3769a666a3ccdd7edd2da98"},"headline":"CCP Strategy Mini Retreat 2025","datePublished":"2025-05-10T13:55:45+00:00","dateModified":"2025-05-10T13:55:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/"},"wordCount":181,"publisher":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#organization"},"image":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg","articleSection":["Blog Post"],"inLanguage":"en"},{"@type":"WebPage","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/","url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/","name":"CCP Strategy Mini Retreat 2025 - CCP Blog","isPartOf":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg","datePublished":"2025-05-10T13:55:45+00:00","dateModified":"2025-05-10T13:55:46+00:00","breadcrumb":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#primaryimage","url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg","contentUrl":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2025\/05\/IMG_5669-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/uncategorized\/ccp-strategy-mini-retreat-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/"},{"@type":"ListItem","position":2,"name":"CCP Strategy Mini Retreat 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#website","url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/","name":"CCP Blog","description":"Consultants Collaborative Partnership Blog","publisher":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#organization","name":"CCP Blog","url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2024\/12\/cropped-ccp-logo-header.png","contentUrl":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-content\/uploads\/2024\/12\/cropped-ccp-logo-header.png","width":61,"height":100,"caption":"CCP Blog"},"image":{"@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/#\/schema\/person\/99025ad5d3769a666a3ccdd7edd2da98","name":"Adeboye Lawal","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfa759dadb0a9b13a23f58e6ccf93f6f5f1032af916b27e195b84bce18a4410e?s=96&d=mm&r=g","caption":"Adeboye Lawal"},"url":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/author\/adeboye\/"}]}},"_links":{"self":[{"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":1,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/posts\/64\/revisions\/74"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/media\/72"}],"wp:attachment":[{"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.consultantscollaborative.com\/ccp-blog\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}